{"id":61665,"date":"2019-04-18T10:02:16","date_gmt":"2019-04-18T10:02:16","guid":{"rendered":"https:\/\/access.sb\/qui-sommes-nous\/"},"modified":"2019-05-22T21:18:47","modified_gmt":"2019-05-22T21:18:47","slug":"why-access","status":"publish","type":"page","link":"https:\/\/www.access.sb\/en\/why-access\/","title":{"rendered":"Why Access?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":20,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"views\/template-who-are-we.blade.php","meta":[],"class_list":["post-61665","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Why Access? - Access<\/title>\n<meta name=\"description\" content=\"Why Access? : la r\u00e9f\u00e9rence sur \u00eele de St Barth\u00e9l\u00e9my =&gt; Access\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.access.sb\/en\/why-access\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Why Access? - Access\" \/>\n<meta property=\"og:description\" content=\"Why Access? : la r\u00e9f\u00e9rence sur \u00eele de St Barth\u00e9l\u00e9my =&gt; Access\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.access.sb\/en\/why-access\/\" \/>\n<meta property=\"og:site_name\" content=\"Access\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-22T21:18:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.access.sb\/en\/why-access\/\",\"url\":\"https:\/\/www.access.sb\/en\/why-access\/\",\"name\":\"Why Access? - Access\",\"isPartOf\":{\"@id\":\"https:\/\/www.access.sb\/en\/#website\"},\"datePublished\":\"2019-04-18T10:02:16+00:00\",\"dateModified\":\"2019-05-22T21:18:47+00:00\",\"description\":\"Why Access? : la r\u00e9f\u00e9rence sur \u00eele de St Barth\u00e9l\u00e9my => Access\",\"breadcrumb\":{\"@id\":\"https:\/\/www.access.sb\/en\/why-access\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.access.sb\/en\/why-access\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.access.sb\/en\/why-access\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.access.sb\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Why Access?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.access.sb\/en\/#website\",\"url\":\"https:\/\/www.access.sb\/en\/\",\"name\":\"Access\",\"description\":\"Les meilleures adresses pour des vacances de prestige\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.access.sb\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Why Access? - Access","description":"Why Access? : la r\u00e9f\u00e9rence sur \u00eele de St Barth\u00e9l\u00e9my => Access","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.access.sb\/en\/why-access\/","og_locale":"en_US","og_type":"article","og_title":"Why Access? - Access","og_description":"Why Access? : la r\u00e9f\u00e9rence sur \u00eele de St Barth\u00e9l\u00e9my => Access","og_url":"https:\/\/www.access.sb\/en\/why-access\/","og_site_name":"Access","article_modified_time":"2019-05-22T21:18:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.access.sb\/en\/why-access\/","url":"https:\/\/www.access.sb\/en\/why-access\/","name":"Why Access? - Access","isPartOf":{"@id":"https:\/\/www.access.sb\/en\/#website"},"datePublished":"2019-04-18T10:02:16+00:00","dateModified":"2019-05-22T21:18:47+00:00","description":"Why Access? : la r\u00e9f\u00e9rence sur \u00eele de St Barth\u00e9l\u00e9my => Access","breadcrumb":{"@id":"https:\/\/www.access.sb\/en\/why-access\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.access.sb\/en\/why-access\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.access.sb\/en\/why-access\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.access.sb\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Why Access?"}]},{"@type":"WebSite","@id":"https:\/\/www.access.sb\/en\/#website","url":"https:\/\/www.access.sb\/en\/","name":"Access","description":"Les meilleures adresses pour des vacances de prestige","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.access.sb\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/pages\/61665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/comments?post=61665"}],"version-history":[{"count":5,"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/pages\/61665\/revisions"}],"predecessor-version":[{"id":82212,"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/pages\/61665\/revisions\/82212"}],"wp:attachment":[{"href":"https:\/\/www.access.sb\/en\/wp-json\/wp\/v2\/media?parent=61665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}